{"id":6523,"date":"2015-09-01T14:04:35","date_gmt":"2015-09-01T12:04:35","guid":{"rendered":"http:\/\/www.aicw.it\/?p=6523"},"modified":"2015-09-01T14:04:35","modified_gmt":"2015-09-01T12:04:35","slug":"bando-3-tappa-italian-slalom-tour-oristano-open-water-challenge-2015","status":"publish","type":"post","link":"https:\/\/www.aicw.it\/index.php\/2015\/09\/01\/bando-3-tappa-italian-slalom-tour-oristano-open-water-challenge-2015\/","title":{"rendered":"Bando 3\u00b0 Tappa Italian Slalom Tour &#8211; Oristano Open Water challenge 2015"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><u><a href=\"http:\/\/www.aicw.it\/wp-content\/uploads\/2015\/06\/log2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-6331 aligncenter\" src=\"http:\/\/www.aicw.it\/wp-content\/uploads\/2015\/06\/log2.jpg\" alt=\"log2\" width=\"120\" height=\"123\" \/><\/a>BANDO di Regata 3\u00b0 tappa ITALIAN SLALOM TOUR 2015<\/u><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>AUTORITA\u2019 ORGANIZZATRICE:<\/strong><\/p>\n<p>CIRCOLO NAUTICO ORISTANO- Porticciolo Turistico Torregrande \u2013 ORISTANO<\/p>\n<p>Tel. 346 0319129 segreteria\u00a0\u00a0\u00a0\u00a0 E-mail <a href=\"mailto:circolonauticooristano@gmail.com\">circolonauticooristano@gmail.com<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 in collaborazione con AICW. <a href=\"mailto:segreteria@aicw.it\">segreteria@aicw.it<\/a><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<ul>\n<li><strong>1) <\/strong><strong>DENOMINAZIONE DELLA MANIFESTAZIONE: <\/strong><\/li>\n<\/ul>\n<p>6\u00b0 OPen water Challenge Oristano 3\u00b0TAPPA ITALIAN SLALOM TOUR 2015<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>2) <\/strong><strong>LOCALITA&#8217;, DATE: <\/strong><\/li>\n<\/ul>\n<p><strong>CIRCOLO NAUTICO ORISTANO<\/strong> &#8211; Ass Sport Dil c\/o la base logistica di\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0 Eolo scuola di Windsurf<strong>\u00a0<\/strong><\/p>\n<p>Venerd\u00ec <strong>11-09-2015<\/strong> Sabato <strong>12-09-2015<\/strong> Domenica<strong> 13-09-2015<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>3) <\/strong><strong>AMMISSIONE, DISCIPLINE E TESSERAMENTO: <\/strong><\/li>\n<\/ul>\n<p>Saranno ammessi\u00a0 massimo 80 concorrenti e ci\u00f2\u00a0per la corretta formazione del tabellone Slalom. In linea di massima si predisporranno percorsi con andature portanti. La scelta del percorso e le caratteristiche della partenza sono a discrezione del Comitato di Regata, secondo le condizioni meteo. Tutti i concorrenti dovranno essere in regola con il tesseramento AICW 2015 nel rispetto delle tipologie indicate sul sito <a href=\"http:\/\/www.aicw.it\">www.aicw.it<\/a> , (che \u00e8 comprensivo dell&#8217;assicurazione RC valida per tutto l\u2019anno solare 2015, come richiesto dalla Normativa Federale) e FIV 2015. Su quest&#8217;ultima tessera devono essere obbligatoriamente presenti la dicitura &#8220;visita medica B&#8221;, comprovante la visita medica sportivo-agonistica e la data di scadenza della visita medica stessa. E\u2019 fatto OBBLIGO ai Soci di essere in regola con il tesseramento FIV entro le 48 ore antecedenti le regate. Non saranno accettate iscrizioni FIV in loco. Per la categoria <strong>UNDER 20<\/strong> <strong>\u201cOPEN\u201d<\/strong> (nati dal 1995 al 2003) l&#8217;ammissione a tutte le regate \u00e8 libera e non sussiste limitazione alcuna al numero degli iscritti. Per quanto riguarda le categorie <strong>Under 17<\/strong> (nati dal 1999 al 2000) e <strong>Under 15<\/strong> (nati dal 2001 al 2003) la Regata \u00e8 riservata alle Tavole a Vela della RRD <strong>Fire Race W-Tech 120 Club &#8211; One Design<\/strong> e non sussiste limitazione alcuna al numero degli iscritti.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>4) <\/strong><strong>VALIDITA&#8217; DEL CIRCUITO E CATEGORIE:<\/strong><\/li>\n<\/ul>\n<p>Assoluta, * maschile; * femminile; * Masters (nati dal 1979 al 1970), GrandMasters (nati nel 1969 e anni precedenti); Juniores (nati dal 1995 al 2003 che non abbiano compiuti 20 anni). Le categorie hanno validit\u00e0 con la partecipazione di almeno tre concorrenti della categoria in questione. Ai fini dell\u2019assegnazione del titolo Master o GrandMaster si specifica che sono due titoli separati e non cumulabili.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>5) <\/strong><strong>REGOLAMENTI:<\/strong><\/li>\n<\/ul>\n<p>Le regate saranno disputate in base al *Regolamento ISAF 2013-2016, alle Istruzioni di Regata ed agli eventuali Comunicati emessi dal CdR.<\/p>\n<p>A discrezione del Comitato di Regata e\/o del Comitato organizzatore, potr\u00e0 essere previsto l&#8217;arbitraggio diretto, mediante UdR presenti alle boe: in tal caso verr\u00e0 applicata la regola del &#8220;<strong><em>navigare pericolosamente<\/em><\/strong>&#8221; basata sul seguente principio: <strong>\u201c<\/strong>un concorrente <em>naviga pericolosamente<\/em> quando il suo navigare pu\u00f2 procurare danni materiali e\/o fisici agli altri concorrenti.\u201d Nel caso in cui si applichi il sistema dell&#8217;arbitraggio diretto, l&#8217;UdR o gli UdR giudicheranno le infrazioni alla parte seconda del Regolamento di Regata basandosi esclusivamente sulla regola del &#8220;<em>navigare pericolosamente<\/em>&#8221; e sulla regola 10 RRS. Le decisioni dell&#8217;UdR o degli UdR saranno inappellabili e non potranno essere oggetto di richiesta di riparazione. Ai fini della stesura delle batterie si far\u00e0 riferimento alla classifica dell\u2019Italian Slalom tour.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>6) <\/strong><strong>STAZZE E MATERIALI:<\/strong><\/li>\n<\/ul>\n<p>Per quanto concerne i materiali, alla regata Slalom possono essere utilizzate tre tavole di produzione di serie secondo la lista pi\u00f9 aggiornata pubblicata dall&#8217;ISAF e sei vele. La larghezza massima delle tavole deve essere di 85 cm.; la dimensione massima delle vele deve essere di 10 mq. Per quanto concerne le pinne, possono essere dichiarate pinne con lunghezza massima 60 cm. senza limitazione del loro numero. Il Comitato di Regata si riserva la possibilit\u00e0 di effettuare controlli casuali per verificare l&#8217;effettiva rispondenza tra il materiale utilizzato in regata e quanto dichiarato sul modulo di iscrizione. Non saranno effettuati controlli ufficiali di stazza, ma, in caso di contestazioni, potr\u00e0 essere richiesto l&#8217;intervento di uno stazzatore, e il costo dell&#8217;operazione verr\u00e0 addebitato al perdente la protesta.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>7) <\/strong><strong>SALVAGENTE:<\/strong><\/li>\n<\/ul>\n<p>E&#8217; fatto obbligo a tutti i concorrenti di indossare un idoneo giubbotto salvagente. Tale obbligo non pu\u00f2 tuttavia costituire oggetto di protesta tra i concorrenti.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>8) <\/strong><strong>PROVE PREVISTE:<\/strong> <strong>Numero di prove \u2013 tempo limite \u2013 target time \u2013 intensit\u00e0 del vento <\/strong>\n<ul>\n<li>Non si possono completare pi\u00f9 di 6 tabelloni al giorno;<\/li>\n<li>Un massimo di 15 tabelloni pu\u00f2 essere portato a termine durante un evento<\/li>\n<li>Tempo limite: i concorrenti che termineranno la batteria con un tempo superiore al 100% del tempo impiegato dal primo concorrente a finire la batteria, saranno qualificati DNF;<\/li>\n<li>Il target time per un percorso downwind \u00e8 di 4 minuti;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Vento limite: se durante l\u2019ultimo minuto prima della partenza l\u2019intensit\u00e0 del vento scende sotto gli 11 nodi il CdR deve differire la partenza: una nuova procedura di partenza sar\u00e0 iniziata non appena le condizioni del vento siano sufficienti per garantire una regolare partenza.<\/p>\n<ul>\n<li><strong>9) <\/strong><strong>PROGRAMMA:<\/strong><\/li>\n<\/ul>\n<p>L\u2019orario previsto per il segnale di avviso della prima prova \u00e8 fissato alle ore 11:00 del primo giorno di regata. I concorrenti dovranno essere a disposizione del Comitato di Regata alla mattina del primo giorno di regata per lo Skipper&#8217;s meeting, in un orario che verr\u00e0 collocato all&#8217;Albo ufficiale dei comunicati entro le ore 20.00 del giorno precedente. Durante lo Skipper&#8217;s meeting di ogni giorno verr\u00e0 comunicato il programma orientativo della giornata. Tuttavia, salvo diverse disposizioni affisse all&#8217;Albo ufficiale dei comunicati entro le ore 12.00 dell&#8217;ultimo giorno di gara previsto, nessuna prova potr\u00e0 avere inizio dopo le ore 19.00 del medesimo giorno.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>10) <\/strong><strong>SISTEMA DI PUNTEGGIO E SCARTI:<\/strong><\/li>\n<\/ul>\n<p>Verr\u00e0 applicata l&#8217;appendice A2 cos\u00ec come modificata dall&#8217;appendice &#8220;B&#8221; con le seguenti modifiche:<\/p>\n<p>al primo classificato verr\u00e0 assegnato il punteggio di 0,7 punti.<\/p>\n<p>scarti: da 1 a 3 tabelloni: nessuno scarto; da 4 a 6 tabelloni: 1 scarto; da 7 a 8 tabelloni: 2 scarti; oltre 9 tabelloni: 3 scarti.<\/p>\n<p>Ai fini degli scarti di tappa: da 1 a 3 tappe 0 scarti; da 4 a 5 tappe 1 scarto.<\/p>\n<p>Ai fini dell\u2019assegnazione del Tour, si utilizzer\u00e0 il sistema a punti, riceveranno punti i primi 64 concorrenti, secondo la classificazione<\/p>\n<p>1-2100; 2-2067; 3-2034; 4-2001; 5-1968; 6-1935; 7-1902; 8-1869; 9-1836; 10-1803; 11-1770; 12-1737; 13-1704; 14-1671; 15-1638; 16-1605; 17-1572; 18-1539; 19-1506; 20-1473; 21-1440; 22-1407; 23-1374; 24-1341; 26-1275; 27-1242; 28-1209; 29-1176; 30-1143; 31-1110; 32-1077; 33-1044; 34-1011; 35-978; 36-945; 37-912; 38-879; 39-846; 40-813; 41-780; 42-747; 43-714; 44-681; 45-648; 46-615; 47-582; 48-549; 49-516; 50-483; 51-450; 52-417; 53-384; 54-351; 55-318; 56-285; 57-252; 58-219; 59-186; 60-153; 61-120; 62-87; 63-54; 64-21.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>11) <\/strong><strong>ISTRUZIONI DI REGATA:<\/strong> Saranno a disposizione dei concorrenti all&#8217;atto del perfezionamento dell\u2019iscrizione.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>12) <\/strong><strong>ISCRIZIONI E QUOTE<\/strong>:<\/li>\n<\/ul>\n<p>e\u2019 obbligatoria la prescrizione alla segreteria segreteria@aicw.it e\/o al Circolo organizzatore <em><strong>entro<\/strong><\/em> il<em><strong> LUNED\u00ec 7 Settembre 2015<\/strong><\/em>.<\/p>\n<p>La tassa di iscrizione \u00e8 fissata in <strong>\u20ac. 60<\/strong> <strong>euro. <\/strong>Per gli <strong>Juniores<\/strong> la quota di iscrizione \u00e8 del <strong>50% in meno<\/strong> rispetto alle altre categorie. Estremi per il bonifico diretto: IBAN IT16C0100517400000000000207 intestato ASD Eolo Beach Sport.<\/p>\n<p>Per coloro che si iscriveranno dopo tale data, fatta salva la disponibilit\u00e0 di accettare o meno l&#8217;iscrizione da parte del Circolo organizzatore, la tassa di iscrizione sar\u00e0 maggiorata del <strong>30%<\/strong>. E\u2019 possibile partecipare anche ad un solo giorno di regata, pagando la quota intera e nel caso in cui si svolgano prove al concorrente non presente verr\u00e0 attribuito DNS.<\/p>\n<ul>\n<li><strong>13) <\/strong><strong>PUBBLICITA&#8217;:<\/strong><\/li>\n<\/ul>\n<p>La Regata \u00e8 classificata \u201ca libera sponsorizzazione\u201d. I concorrenti che espongono pubblicit\u00e0 propria dovranno essere in regola con la licenza FIV per l&#8217;esposizione della pubblicit\u00e0 come da:<\/p>\n<p><a href=\"http:\/\/www.federvela.it\/la-federvela\/content\/pubblicit%C3%A0\">http:\/\/www.federvela.it\/la-federvela\/content\/pubblicit\u00e0<\/a><\/p>\n<p>Il Circolo Organizzatore e\/o AICW potr\u00e0 richiedere ai concorrenti di esporre un adesivo,\u00a0 rappresentante il nome dello Sponsor della Manifestazione,\u00a0 su ambedue i lati della vela e\/o sulle pettorine che dovranno essere esposti per l\u2019intera durata della manifestazione, in accordo con la Regulation 20.4 ISAF.<\/p>\n<p>L&#8217;inosservanza di quest&#8217;ultima norma non potr\u00e0 essere oggetto di protesta tra i concorrenti.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>14) <\/strong><strong>MEDIA:<\/strong><\/li>\n<\/ul>\n<p>Con l&#8217;iscrizione a una regata ogni concorrente concede automaticamente agli organizzatori il diritto perpetuo di realizzare, utilizzare e mostrare, in qualsiasi occasione e a discrezione dei medesimi, ogni registrazione audio, immagine fotografica, filmato, ripresa video e TV in diretta o registrata, effettuati durante la suddetta regata alla quale prende parte, senza compenso alcuno. La presenza in acqua di barche di appoggio per i media, cos\u00ec come per gli allenatori o responsabili delle squadre, deve essere autorizzata dal Comitato di Regata.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>15) <\/strong><strong>RESPONSABILITA&#8217;<\/strong>:<\/li>\n<\/ul>\n<p>Come da regola fondamentale 4 i partecipanti alla regata di cui al presente Bando prendono parte alla stessa sotto la loro piena ed esclusiva responsabilit\u00e0, i Concorrenti sono gli unici responsabili per la decisione di prendere parte o di continuare la regata. Gli Organizzatori declinano ogni e qualsiasi responsabilit\u00e0 per danni che possono subire persone e\/o cose, sia in terra che in acqua, in conseguenza della loro partecipazione alla regata di cui al presente Bando di Regata. E\u2019 competenza dei Concorrenti decidere in base alle loro capacit\u00e0, alla forza del vento, allo stato del mare, alle previsioni meteorologiche ed a tutto quanto altro deve essere previsto da un buon marinaio, se uscire in mare e partecipare alla regata, di continuarla ovvero di rinunciare.<\/p>\n<p>&nbsp;<\/p>\n<p>16) <strong>CONDIZIONI AREA DI REGATA:<\/strong><\/p>\n<p>La regata si svolger\u00e0 all&#8217;interno del golfo di Oristano, sicuro e protetto da tutte le direzioni del vento, nello specchio d&#8217;acqua antistante lo stabilimento Eolo. La direzione predominante sia di perturbazione che termico sono di vento da NO, con il mare che si presenta leggermente increspato e anche con forti intensit\u00e0 il chop non \u00e8 mai insidioso . Visto il periodo anche il SO potrebbe presentarsi con un discreto moto ondoso da sx.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.aicw.it\/wp-content\/uploads\/2015\/08\/BANDO-SLALOM-ORISTANO.pdf\">BANDO ITALIAN SLALOM TOUR ORISTANO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BANDO di Regata 3\u00b0 tappa ITALIAN SLALOM TOUR 2015 \u00a0 AUTORITA\u2019 ORGANIZZATRICE: CIRCOLO NAUTICO ORISTANO- Porticciolo Turistico Torregrande \u2013 ORISTANO Tel. 346 0319129 segreteria\u00a0\u00a0\u00a0\u00a0 E-mail circolonauticooristano@gmail.com\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 in collaborazione con AICW. segreteria@aicw.it \u00a0 1) DENOMINAZIONE DELLA MANIFESTAZIONE: 6\u00b0 OPen water Challenge Oristano 3\u00b0TAPPA ITALIAN SLALOM TOUR 2015 &nbsp; 2) LOCALITA&#8217;, DATE: CIRCOLO NAUTICO ORISTANO &#8211; Ass [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6523","post","type-post","status-publish","format-standard","category-bandi-regata","czr-hentry"],"_links":{"self":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/6523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/comments?post=6523"}],"version-history":[{"count":0,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/6523\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media?parent=6523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/categories?post=6523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/tags?post=6523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}