{"id":16649,"date":"2024-03-19T09:05:13","date_gmt":"2024-03-19T08:05:13","guid":{"rendered":"http:\/\/www.aicw.it\/?p=16649"},"modified":"2024-04-11T16:36:34","modified_gmt":"2024-04-11T14:36:34","slug":"candidature-nuovo-quadriennio-2","status":"publish","type":"post","link":"https:\/\/www.aicw.it\/index.php\/2024\/03\/19\/candidature-nuovo-quadriennio-2\/","title":{"rendered":"Candidature nuovo Quadriennio"},"content":{"rendered":"<div class=\"elementToProof\">Egregi Soci,<\/div>\n<div><\/div>\n<div>come penso saprete con le Olimpiadi di Parigi 2024 decadranno per scadenza dei termini tutte le cariche dirigenziali di tutte le Federazioni ed Associazioni collegate; pertanto, ode pervenire alla formazione di un nuovo Consiglio Direttivo di AICW, ai sensi dell\u2019art. 15.1 del Regolamento allo Statuto della nostra ASD, Vi invito, entro e non oltre il 30 Aprile 2024 p.v., ad inviare alla mail <a href=\"mailto:segreteria@aicw.it\">segreteria@aicw.it<\/a> la Vostra eventuale candidatura a Presidente o Consigliere, per il futuro Consiglio Direttivo che governer\u00e0 l\u2019Associazione nel quadriennio Olimpico 2024-2028.<\/div>\n<div><\/div>\n<div>Le elezioni, salvo problemi, si terranno durante l&#8217;ultima Tappa del Campionato Italiano Assoluto e Giovanile Salom Fin &amp; Foil 2024, che si svolger\u00e0 all&#8217;Isola D&#8217;Elba dal 3 al 6 Ottobre 2024.<\/div>\n<div><\/div>\n<div>Cordiali saluti<\/div>\n<div class=\"elementToProof\">Il Presidente<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Egregi Soci, come penso saprete con le Olimpiadi di Parigi 2024 decadranno per scadenza dei termini tutte le cariche dirigenziali di tutte le Federazioni ed Associazioni collegate; pertanto, ode pervenire alla formazione di un nuovo Consiglio Direttivo di AICW, ai sensi dell\u2019art. 15.1 del Regolamento allo Statuto della nostra ASD, Vi invito, entro e non [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-16649","post","type-post","status-publish","format-standard","has-post-thumbnail","category-latest-news","czr-hentry"],"_links":{"self":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/comments?post=16649"}],"version-history":[{"count":1,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16649\/revisions"}],"predecessor-version":[{"id":16650,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16649\/revisions\/16650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media\/14915"}],"wp:attachment":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media?parent=16649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/categories?post=16649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/tags?post=16649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}