{"id":16081,"date":"2023-07-11T17:30:51","date_gmt":"2023-07-11T15:30:51","guid":{"rendered":"http:\/\/www.aicw.it\/?p=16081"},"modified":"2023-07-12T10:38:11","modified_gmt":"2023-07-12T08:38:11","slug":"iii-tappa-campionato-italiano-giovanile-e-assoluto-fiv-aicw-30-giugno-2-luglio-2023-twkc-talamone","status":"publish","type":"post","link":"https:\/\/www.aicw.it\/index.php\/2023\/07\/11\/iii-tappa-campionato-italiano-giovanile-e-assoluto-fiv-aicw-30-giugno-2-luglio-2023-twkc-talamone\/","title":{"rendered":"III Tappa Campionato Italiano Giovanile e Assoluto FIV\/AICW  30 Giugno \u2013 2 Luglio\u00a0 2023 \u2013 TWKC Talamone"},"content":{"rendered":"<h3><em>Talamone non tradisce, tre giorni di regate, ospiti di TWKC, un folto numero di partecipanti, e il foil che, in questa tappa, la fa da padrone, con sette regate disputate, e una sola prova pinna, complice un vento da Maestrale discontinuo, che non ha, di certo, aiutato gli specialisti fin.\u00a0<\/em><\/h3>\n<p>&nbsp;<\/p>\n<p>Talamone \u00e8 una di quelle location, che raramente delude le aspettative, nonostante il tempo un po\u2019 incerto della prima giornata e un Maestrale incostante per la prova Fin, la tappa ha regalato, soprattutto per i ragazzi del Foil, belle emozioni, e sette prove portate a termine.<\/p>\n<p>Anche questa volta numerosissimi i giovani partecipanti, un bel ritorno alle gare di Francesco Simeoni, lontano dalle competizioni da due anni, che ha dominato il tabellone foil U20, con cinque prime posizioni su sette regate disputate! L\u2019U20 Michele Laurenza, si conferma il talento da tenere d\u2019occhio, secondo U20 foil e terzo nell\u2019assoluto foil.<\/p>\n<p>Nelle gare Under 17-15 foil, Federico Calcaterra (U17), colleziona sei prime posizioni, e il giovanissimo U15, Matteo Landi, si piazza in terza posizione, Martina Focante, U17, \u00e8 la prima delle ragazze, seguita dalla giovanissima U15, Ginevra Giunti e dalla U17 Giulia Bonura.<\/p>\n<p>Nell\u2019assoluto \u00e8 il senior Daniele Benedetti a collezionare tutte le prime posizioni in ogni regata disputata, seguito dall\u2019altro senior Christopher Frank, secondo nelle sette prove disputate, e dal talento U20, \u00a0Michele Laurenza, in terza posizione.<\/p>\n<p>Sul fronte tabellone pinna, il vento da Maestrale, sui 16 nodi, e i continui cambi di direzione, non hanno facilitato lo svolgersi delle regate, facendo s\u00ec che si portasse a termine una sola regata Fin per assoluto e U17-15. Christopher Frank, nell\u2019assoluto, ha concluso sul gradino pi\u00f9 alto del podio, seguito dall\u2019U20 Matteo Righetti e dal senior Giulio Milianelli. Unica donna in gara, Aurora Vannucci, alla quale abbiamo chiesto un suo parere sulla tappa appena disputata. Tra i giovanissimi, \u00e8 l\u2019U15 Arturo Schinin\u00e0 a portare a casa la prima posizione, seguito dall\u2019U17 Davide Arena e dall\u2019altro giovanissimo talento U15, Michele Bonsanto.<\/p>\n<p>&nbsp;<\/p>\n<p>Abbiamo chiesto qualche parere, come di consueto, ai protagonisti della tappa, tutti entusiasti dell\u2019organizzazione del circolo TWKC, in attesa del rientro alle competizioni Slalom, il 15-17 Settembre, a Calambrone, dopo la consueta pausa estiva.<\/p>\n<p>Testo di Aurora Vannucci, Daniele Benedetti, Christopher Frank, Francesco Simeoni, Simone Santoni, Roberta Pala<\/p>\n<p>&nbsp;<\/p>\n<p>foto di Tommaso Landi<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Assoluto Slalom Pinna FIV\/AICW, podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Giulio Milianelli, ITA 206, senior<\/li>\n<li>Massimiliano Brunetti, ITA 95, master<\/li>\n<li>Matteo Righetti, ITA 885, Under 20<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Assoluto Slalom Foil FIV\/AICW, podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Alessandro Ristori, ITA 451, senior<\/li>\n<li>Giulio Milianelli, ITA 206, senior<\/li>\n<li>Carmine Navarra, ITA 881, senior<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Under 20 Pinna<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Michele Laurenza, ITA 9114<\/li>\n<li>Matteo Righetti, ITA 885<\/li>\n<li>Gabriele Prosperi, ITA 278<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Under 20 Foil<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Michele Laurenza, ITA 9114<\/li>\n<li>Gabriele Prosperi, ITA 278<\/li>\n<li>Samuele Basso, ITA 115<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>In campo femminile Elena de Fazi, ITA 747, \u00e8 in nona posizione nella classifica generale under 20.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Giovanile Pinna Under 17<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Matteo della Fiorentina, ITA 315<\/li>\n<li>Davide Arena, ITA 122<\/li>\n<li>Giovanni Landi, ITA 7116<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>In campo femminile, Diana Vicari, ITA 820, \u00e8 quinta in classifica generale U17<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Giovanile Foil Under 17<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Federico Calcaterra, ITA 819<\/li>\n<li>Gabriele Rosa, ITA 178<\/li>\n<li>Giovanni Landi, ITA 7116<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>In campo femminile Martina Focante, ITA 948, \u00e8 in quinta posizione nella classifica generale under 17.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Giovanile Pinna Under 15<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Arturo Schinin\u00e0, ITA 818<\/li>\n<li>Michele Bonsanto, ITA 2811<\/li>\n<li>Matteo Landi, ITA 7117<\/li>\n<li>Ginevra Giunti, ITA 321<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Campionato Italiano Slalom Giovanile Foil Under 15<\/strong>, <strong>podio provvisorio dopo tre tappe:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li>Matteo Landi, ITA 7117<\/li>\n<li>Arturo Schinin\u00e0, ITA 818<\/li>\n<li>Ginevra Giunti, ITA 321<\/li>\n<li>Michele Bonsanto, ITA 2811<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Per le classifiche complete: http:\/\/www.aicw.it\/index.php\/classifiche-2023\/<\/p>\n<p>&nbsp;<\/p>\n<p>La parola all\u2019organizzatore TWKC, Simone Santoni<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cSono stati tre giorni caratterizzati da regate per tutte le giornate di gara, dal mio punto di vista non poteva andare meglio. Sicuramente, il foil rappresenta il futuro del mondo delle regate, perch\u00e9 il limite di vento \u00e8 inferiore, e si riescono a fare regate anche con venti marginali, gi\u00e0 con 7 nodi, si riesce a fare slalom con il windsurf, e volano tutti, anche i pi\u00f9 pesanti.<\/em><\/p>\n<p><em>Alcuni regatanti erano impegnati nelle gare internazionali, ma i giovani e alcuni riders forti, tra cui Benedetti e Frank, hanno dato vita a bellissime prove.<\/em><\/p>\n<p><em>Alla fine, abbiamo fatto due giorni di regate con il foil e un giorno con la pinna, cos\u00ec siamo riusciti a portare a casa le gare in entrambe le specialit\u00e0, purtroppo per la pinna. ci sono state tante prove annullate, era il primo giorno in cui entrava il Maestrale e le condizioni non erano ottimali.<\/em><\/p>\n<p><em>Ho visto tanti nuovi giovani, nuovi appassionati, mi sembra che la tendenza, parlo anche dell\u2019esperienza come scuola, sia di un notevole aumento dei ragazzi che si avvicinano al windsurf, con un incremento sensibile rispetto agli scorsi anni, spero che questo porti ad avere molti giovanissimi che si avvicinano allo sport, con un incremento di partecipazione alle regate dei prossimi anni.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aurora Vannucci, senior, ITA-253<\/strong><\/p>\n<p><em>\u201c\u00c8 stato un weekend all&#8217;insegna del divertimento e dell&#8217;adrenalina. Peccato che per chi, come me, ha gareggiato soltanto con la pinna, il vento non \u00e8 stato dalla nostra parte, ma la location di Talamone regala sempre una piacevole attesa che arrivi il termico&#8230;<\/em><\/p>\n<p><em>La regata per la terza tappa italiana \u00e8 stata molto stimolante, tanti atleti pronti a battersi, e allo stesso tempo, spirito di convivialit\u00e0, che ci ha accompagnato per tre giorni. I ragazzi del circolo sono sempre stati sorridenti e ospitali, per non parlare della cena al top!<\/em><\/p>\n<p><em>Unica pecca, come dicevo prima, per quanto riguarda il vento, i giudici hanno annullato molte partenze, poich\u00e9 il campo di regata era proprio in mezzo a un &#8220;buco&#8221; di vento, ma dopo mille disappunti e discussioni, siamo arrivati a un finale. In generale, anche se senza risultato, mi \u00e8 piaciuto l&#8217;ambiente e lo stimolo a migliorarsi.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Christopher Frank, senior, ITA-211<\/strong><\/p>\n<p><em>\u201cTalamone, come al solito, non delude mai. Noi siamo andati, con i ragazzi, una giornata prima, per allenamento, sono stati quattro giorni in acqua, condizioni diverse, venti pi\u00f9 leggeri, pi\u00f9 forti, direzioni differenti, un po\u2019 da mare, un po\u2019 da terra, ed \u00e8 stato molto utile, per noi, per migliorare. Inoltre, arrivavamo dal week end precedente, in cui avevamo avuto lo zonale, e anche questo ci \u00e8 stato di aiuto per prepararci al meglio. Io, personalmente, sono molto contento, anche perch\u00e9 quest\u2019anno non sono super allenato, perch\u00e9 il lavoro \u00e8 tanto, e sto navigando bene, sono contento, riesco a stare concentrato in gara anche se seguo i ragazzi, non \u00e8 semplice, sono tanti da guardare, ognuno ha i suoi piccoli problemi. Siamo molto contenti dei ragazzi, riusciamo a gareggiare con loro, sono indipendenti, sia in acqua sia a terra, sanno fare tutto, sanno organizzarsi, leggere le varie condizioni, sanno gestire bene la regata, sia come forze, energie, resistenza, sia dal punto tattico, sapendo leggere il campo di regata nelle varie condizioni. Stiamo migliorando tanto, diciamo che sono solo due anni che stiamo allenando questo gruppo slalom e anche loro stanno provando che l\u2019allenamento, il navigare in gruppo, con le boe, paga e risultati arrivano. Ancora ci manca un po\u2019 di esperienza, facciamo ancora un po\u2019 di errori, ma \u00e8 giusto cos\u00ec, sono giovani, soprattutto c\u2019\u00e8 il divertimento dietro, c\u2019\u00e8 la passione, e questo \u00e8 quello che serve, poi, se a uno piace quello che fa, viene da solo il farlo bene, come tutti gli sport, ci vuole dedizione, determinazione, c\u2019\u00e8 tanto lavoro dietro. Abbiamo portato a casa un bel po\u2019 di coppe, siamo contenti, speriamo che qual che ragazza si aggiunga, perch\u00e9 sono praticamente solo le nostre, e sono quasi tutte molto giovani. Dobbiamo, in generale, migliorare sulla pinna, ma sul foil siamo molto competitivi. Sono molto contento della prestazione di Laurenza, terzo nell\u2019assoluto foil, un ottimo risultato, lui \u00e8 competitivo non solo nei giovani, ma anche nei grandi, quindi iniziamo a guardare anche verso l\u2019assoluto\u2026<\/em><\/p>\n<p><em>Ci vediamo a breve, a Calambrone, due mesi volano\u2026 \u201c<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Daniele Benedetti, senior, ITA-60<\/strong><\/p>\n<p><em>\u201c\u00c8 stata una tappa coinvolgente dall\u2019inizio alla fine, e ho avuto l\u2019occasione di sfruttare questa gara come allenamento in vista dei miei futuri eventi PWA, tra cui Fuerteventura alla fine del mese. Durante i giorni di gara, mi sentivo molto veloce e con il setting giusto, infatti sono riuscito a vincere tutte le prove foil. Talamone, di certo, \u00e8 uno dei pochi posti in Italia dove il vento \u00e8 una garanzia, per questo spero sia possibile organizzare altre gare di livello in questa localit\u00e0.<\/em><\/p>\n<p><em>Infine, volevo fare i miei complimenti al Presidente della classe AICW, Cristiano Siringo, e a tutto lo staff, per la magnifica organizzazione, sono riuscito a capire e vedere veramente quanto impegno e quanta passione ci mettano dietro ad un evento del genere. Sicuramente sar\u00f2 presente ai prossimi appuntamenti della stagione! A presto!\u201d<\/em><\/p>\n<p><strong>Francesco Simeoni, under 20, ITA-123<\/strong><\/p>\n<p>\u201cErano due anni che non partecipavo a gare di slalom, per dedicarmi all\u2019universit\u00e0, e sono rientrato proprio in occasione della gara di Talamone, conquistando il primo posto nella categoria Under 20. Ho subito sentito che avevo ancora il feeling giusto con la tavola e con il foil. Sono state tre giornate molto intense, con ben sette prove con il foil, purtroppo non siamo riusciti a fare le prove Under 20 di pinna a causa dei continui salti di vento, ma sono stato comunque felice del risultato ottenuto in foil!\u201d<\/p>\n<div id='gallery-1' class='czr-gallery row flex-row czr-gallery-style gallery galleryid-16081 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/daniele-benedetti-ita60-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/daniele-benedetti-ita60-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/daniele-benedetti-ita60-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/daniele-benedetti-ita60-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5608-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5608-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5608-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5608-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5617-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5617-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5617-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5617-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5629-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5629-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5629-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5629-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5645-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5645-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5645-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5645-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5646-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5646-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5646-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5646-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5648-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5648-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5648-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5648-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5649-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5649-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5649-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5649-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5665-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5665-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5665-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5665-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5671-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5671-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5671-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5671-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5672-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5672-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5672-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5672-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5746-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5746-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5746-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5746-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5751-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5751-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5751-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5751-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5766-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5766-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5766-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5766-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5795-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5795-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5795-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5795-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5808-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5808-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5808-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5808-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5881-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5881-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5881-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5881-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5890-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5890-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5890-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5890-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5893-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5893-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5893-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5893-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5900-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5900-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5900-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5900-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5902-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5905-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5905-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5905-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5905-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5933-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5933-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5933-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5933-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5937-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5937-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5937-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5937-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5946-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5946-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5946-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5946-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5961-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5961-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5961-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5961-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5973-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5973-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5973-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5973-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5980-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5980-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5980-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN5980-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6037-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6037-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6037-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6037-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6038-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6038-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6038-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6038-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6046-2-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6046-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6046-2-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6046-2-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6270-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6270-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6270-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6270-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6280-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6280-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6280-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6280-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6297-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6297-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6297-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6297-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6300-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6300-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6300-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6300-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6344-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6344-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6344-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6344-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6370-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6370-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6370-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6370-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6391-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6391-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6391-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6391-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6413-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6413-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6413-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6413-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6421-2-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6421-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6421-2-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6421-2-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6433-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6433-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6433-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6433-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6451-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6451-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6451-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6451-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6459-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6459-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6459-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6459-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6503-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6503-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6503-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6503-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6505-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6505-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6505-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6505-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6511-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6511-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6511-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6511-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6515-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6515-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6515-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6515-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6517-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6517-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6517-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6517-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6518-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6518-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6518-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6518-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6520-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6520-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6520-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6520-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6523-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6523-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6523-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6523-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6526-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6526-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6526-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6526-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6527-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6527-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6527-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6527-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6530-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6530-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6530-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6530-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6532-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6532-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6532-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6532-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6534-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6534-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6534-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/DSCN6534-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-1-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-1-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-1-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/calcaterra-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/schinina\u0300-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure><figure class='gallery-item col col-auto'>\r\n                        <div class='gallery-icon landscape czr-gallery-icon'>\r\n                              <a data-lb-type=\"grouped-gallery\" href=https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-scaled.jpg class=\"bg-link\"><\/a><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" sizes=\"auto, (min-width: 1200px) 255px, (min-width: 992px) 210px, (min-width: 768px) 150px, (min-width: 576px) 105px, calc( 50vw - 30px )\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-150x150.jpg 150w, https:\/\/www.aicw.it\/wp-content\/uploads\/2023\/07\/martina-focante-510x510.jpg 510w\" \/>\r\n                        <\/div><\/figure>\r\n                  <\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talamone non tradisce, tre giorni di regate, ospiti di TWKC, un folto numero di partecipanti, e il foil che, in questa tappa, la fa da padrone, con sette regate disputate, e una sola prova pinna, complice un vento da Maestrale discontinuo, che non ha, di certo, aiutato gli specialisti fin.\u00a0 &nbsp; Talamone \u00e8 una di [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":{"0":"post-16081","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-latest-news","7":"category-news","8":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/comments?post=16081"}],"version-history":[{"count":4,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16081\/revisions"}],"predecessor-version":[{"id":16207,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/16081\/revisions\/16207"}],"wp:attachment":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media?parent=16081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/categories?post=16081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/tags?post=16081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}