{"id":14586,"date":"2022-02-03T11:37:38","date_gmt":"2022-02-03T10:37:38","guid":{"rendered":"http:\/\/www.aicw.it\/?p=14586"},"modified":"2022-03-01T10:35:02","modified_gmt":"2022-03-01T09:35:02","slug":"bando-campionato-italiano-wave-2022","status":"publish","type":"post","link":"https:\/\/www.aicw.it\/index.php\/2022\/02\/03\/bando-campionato-italiano-wave-2022\/","title":{"rendered":"BANDO CAMPIONATO ITALIANO WAVE 2022"},"content":{"rendered":"<h3 style=\"text-align: center;\"><strong>CIRCOLO NAUTICO ORISTANO<\/strong><\/h3>\n<h3 style=\"text-align: center;\"><strong>(su delega della FIV -Federazione Italiana Vela- e in collaborazione con A.I.C.W.<\/strong><\/h3>\n<h3 style=\"text-align: center;\"><strong>E<\/strong><\/h3>\n<h3 style=\"text-align: center;\"><strong>Assoc. Sport. Dilett. Velica Ladispoli- Banzai\u00a0 A.S.D.<\/strong><\/h3>\n<h3 style=\"text-align: center;\"><strong>(su delega della FIV -Federazione Italiana Vela- e in collaborazione con A.I.C.W<\/strong>.<\/h3>\n<h1 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>C<\/strong><strong>ampionato Italiano WAVE 2022<\/strong><\/span><\/h1>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>1^ Tappa Funtana Meiga Waiting Period dal 1\/03\/2022 al 30\/04\/2022<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>2^ Tappa Banzai Waiting Period dal 01\/10\/2022 al 15\/11\/2022 <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>(Campionato Italiano Wave Open 2022 A CHIAMATA)<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\">BANDO DI REGATA<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong><em>Le attivit\u00e0 di regate dovranno essere svolte secondo le disposizioni in materia di contrasto e contenimento di diffusione del COVID-19 emanate dalla FIV che il Circolo Organizzatore attiver\u00e0 e a cui i tesserati partecipanti si dovranno attenere sotto la vigilanza da parte del Comitato Organizzatore medesimo.<\/em><\/strong><\/p>\n<p><strong><em>Eventuali casi di COVID-19 che dovessero essere rilevati nel corso della manifestazione saranno denunciati dal Circolo Organizzatore ai competenti Organi Sanitari preposti.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nel presente Bando di Regata e nelle successive Istruzioni di Regata sono utilizzate le seguenti abbreviazioni:<\/strong><\/p>\n<ul>\n<li>AO &#8211; Comitato Organizzatore, Circolo Organizzatore<\/li>\n<li>AUC &#8211; Albo Ufficiale dei Comunicati<\/li>\n<li>CdP &#8211; Comitato delle Proteste<\/li>\n<li>CdR &#8211; Comitato di Regata<\/li>\n<li>CIS &#8211; Codice internazionale dei segnali<\/li>\n<li>CT &#8211; Comitato Tecnico<\/li>\n<li>IdR &#8211; Istruzioni di Regata<\/li>\n<li>RRS &#8211; Regole di Regata della Vela World Sailing (WS) 2021-2024 ovvero Regola<\/li>\n<li>SR &#8211; Segreteria di Regata<\/li>\n<li>WS &#8211; World Sailing<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Notazioni ai punti del Bando di Regata e delle successive Istruzioni di Regata:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"34\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0DP<\/strong><\/td>\n<td width=\"607\">Regole per le quali le penalit\u00e0 sono a discrezione del Comitato delle Proteste.<\/td>\n<\/tr>\n<tr>\n<td width=\"34\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0NP<\/strong><\/td>\n<td width=\"607\">Regole che non possono essere oggetto di protesta barca contro barca (modifica la RRS 60.1(a)).<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a0<\/strong><\/p>\n<ol>\n<li><strong>1<\/strong><strong>. REGOLE <\/strong><\/li>\n<\/ol>\n<p>1.1 L\u2019evento sar\u00e0 disciplinato dalle Regole definite nelle Regole di Regata della Vela (WS) in vigore e le eventuali Prescrizioni FIV.<\/p>\n<p>1.2 La vigente Normativa FIV per l\u2019Attivit\u00e0 Sportiva Organizzata in Italia.<\/p>\n<p>1.3 Le EXPRESSION CHAMPIONSHIP RULES ( <a href=\"https:\/\/www.ifcaclass.com\/wp-content\/uploads\/2017\/02\/EXPRESSION-CHAMPIONSHIPRULES-2017.pdf\">https:\/\/www.ifcaclass.com\/wp-content\/uploads\/2017\/02\/EXPRESSION-CHAMPIONSHIPRULES-2017.pdf<\/a> )<\/p>\n<p>1.4 [DP][NP] Il \u201cPROTOCOLLO DI REGOLAMENTAZIONE DELLE MISURE PER IL CONTRASTO ED IL CONTENIMENTO DELLA DIFFUSIONE DEL COVID-19 NELLE SOCIET\u00c0 E ASSOCIAZIONI SPORTIVE AFFILIATE\u201d, versione in vigore &#8211; da qui in avanti indicato come \u201cPROTOCOLLO\u201d. La penalit\u00e0 per una infrazione al Protocollo sar\u00e0 al massimo del 10%. La percentuale sar\u00e0 calcolata rispetto alla posizione d\u2019arrivo della barca nelle prove di giornata in cui \u00e8 stata commessa l\u2019infrazione, oppure rispetto alla posizione acquisita nella prova pi\u00f9 prossima nel tempo rispetto a quando \u00e8 stata commessa l\u2019infrazione.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li><strong>ISTRUZIONI DI REGATA<\/strong><\/li>\n<\/ol>\n<p>Le Istruzioni di Regata saranno disponibili solo online al seguente link www.aicw.it entro la chiamata \u00a0ufficiale della manifestazione.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"3\">\n<li><strong>COMUNICATI<\/strong><\/li>\n<\/ol>\n<p>L\u2019albo ufficiale dei comunicati \u00e8 accessibile al seguente link www.aicw.it<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"4\">\n<li><strong>ELEGIBILITA\u2019<\/strong><\/li>\n<\/ol>\n<p>L&#8217;ammissione a tutte le regate sar\u00e0 chiusa al raggiungimento del 32\u00b0 concorrente; sono ammessi di diritto coloro i quali rientrano nella ranking wave 2021 o precedenti, <strong><u>previa conferma di regolare iscrizione entro 2 giorni dalla singola tappa e dalla chiamata con semaforo verde<\/u><\/strong>, i residui posti, compresi quelli non confermati della detta ranking 2021 o precedenti, verranno assegnati secondo l&#8217;inderogabile principio dell&#8217;ordine di presentazione delle iscrizioni.<\/p>\n<p>Eventuali ulteriori iscritti vanno a costituire una lista di attesa dalla quale sar\u00e0 possibile attingere nominativi nel caso in cui Atleti ricompresi nei primi 32 non si presentassero alla ratifica.<\/p>\n<p>A insindacabile giudizio del Comitato di Regata potr\u00e0 essere presa in considerazione la possibilit\u00e0 di accettare un numero di partecipanti superiore a 32.<\/p>\n<p>La scelta del Campo di Regata e le caratteristiche della partenza sono a discrezione del Comitato di Regata, secondo le condizioni meteo.<\/p>\n<p>Tutti i concorrenti dovranno essere in regola con il tesseramento AICW e FIV 2022 con apposta la dicitura \u201cVisita medica B\u201d (agonistica), Assegnazione numero velico AICW per il 2022, Tessera valida d\u2019iscrizione alla AICW per l\u2019anno 2022. E\u2019 OBBLIGATORIO, per tutti i Soci sia Senior che Master e GM, il tesseramento quale Socio \u201cORDINARIO\u201d e\/o ARTISTICO. Non verranno ammesse altre tipologie di tesseramento.<\/p>\n<p>NON VERRANNO EFFETTUATI TESSERAMENTI AICW e FIV IN SEDE DI REGATA.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"5\">\n<li><strong> VALIDITA&#8217; DELLA CATEGORIA E SUDDIVISIONI<\/strong><\/li>\n<\/ol>\n<p>Wave Open; le eventuali categorie hanno validit\u00e0 con la partecipazione di almeno tre concorrenti delle categorie.<\/p>\n<p>La validit\u00e0 della gara \u00e8 subordinata alla disputa di almeno una prova sull\u2019arco delle giornate di regata. Il titolo di Campione Italiano sar\u00e0 assegnato solo se alla manifestazione prenderanno parte non meno di 15 concorrenti.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"6\">\n<li><strong> ISCRIZIONI E QUOTE<\/strong>:<\/li>\n<\/ol>\n<p>Le iscrizioni dovranno essere effettuate tramite <a href=\"https:\/\/form.jotform.com\/220265899074364\">MODULO ONLINE<\/a> sul sito AICW e A COMPLETAMENTO tramite la piattaforma elettronica FIV in uso e\/o segreteria@aicw.it entro e non oltre 2 giorni dall\u2019inizio delle regate.<\/p>\n<p>Entro tale data gli equipaggi dovranno versare la relativa tassa di iscrizione alla singola tappa del Campionato Italiano di \u20ac 80 Euro, al Comitato Organizzatore a mezzo di bonifico bancario intestato a: Associazione Italiana Classi Windsurf, conto corrente n. 793, presso Banco San Geminiano e San Prospero Gruppo Banco Popolare, Filiale di Lugo di Romagna.<\/p>\n<p>IBAN: IT75W0503423801000000000793 Indicando in causale:\u00a0 CAMPIONATO ITALIANO WAVE 2022, Numero Velico ITA-<\/p>\n<p>In caso di un unico Bonifico per pi\u00f9 imbarcazioni indicare i numeri velici di tutte le imbarcazioni.<\/p>\n<p>Dovr\u00e0 essere inviata, in un\u2019unica mail al seguente indirizzo:<\/p>\n<p><strong><u>1\u00b0 tappa:<\/u><\/strong><\/p>\n<p><a href=\"mailto:circolonauticooristano@gmail.com\">circolonauticooristano@gmail.com<\/a> e segreteria@aicw.it indicando in oggetto &#8211; DOCUMENTI NUMERO VELICO -, e la sotto elencata documentazione:<\/p>\n<ul>\n<li>Ricevuta della tassa di iscrizione;<\/li>\n<li>Tessera AICW 2022;<\/li>\n<li>Assicurazione RC con copertura minima come da Norme FIV per l\u2019Attivit\u00e0 Sportiva Nazionale Organizzata in Italia 2022 (non necessaria per chi in possesso di tessera FIV Plus e\/o AICW);<\/li>\n<li>Licenza FIV per la pubblicit\u00e0 in corso di validit\u00e0 (ove ricorra)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>2\u00b0 tappa<\/u><\/strong><\/p>\n<p><a href=\"mailto:info@assovelica.it\">info@assovelica.it<\/a> \u00a0e segreteria@aicw.it indicando in oggetto &#8211; DOCUMENTI NUMERO VELICO -, e la sotto elencata documentazione:<\/p>\n<ul>\n<li>Ricevuta della tassa di iscrizione;<\/li>\n<li>Tessera AICW 2022<\/li>\n<li>Assicurazione RC con copertura minima come da Norme FIV per l\u2019Attivit\u00e0 Sportiva Nazionale Organizzata in Italia 2022 (non necessaria per chi in possesso di tessera FIV Plus e\/o AICW);<\/li>\n<li>Licenza FIV per la pubblicit\u00e0 in corso di validit\u00e0 (ove ricorra)<\/li>\n<\/ul>\n<p>Al momento del perfezionamento dell\u2019iscrizione chi avr\u00e0 effettuato l&#8217;iscrizione tramite piattaforma FIV o sito internet correttamente e inviato tutta la documentazione richiesta in una unica mail all\u2019indirizzo sopra citato non avr\u00e0 altra documentazione da presentare. Non sar\u00e0 inoltre necessario firmare il modulo di liberatoria, accettazione informativa privacy e cessione diritti foto e video della manifestazione.<\/p>\n<p>Chi avr\u00e0 inviato la documentazione non completa\/non leggibile\/non idonea o avr\u00e0 visita medica scaduta dovr\u00e0 presentare eventuale documentazione originale integrativa o sostitutiva al momento del perfezionamento della iscrizione compreso il modulo di affido.<\/p>\n<p>&nbsp;<\/p>\n<p>Copia del versamento e di quanto sopra indicato dovr\u00e0 essere inviato in copia al Coordinamento Nazionale AICW alla mail: segreteria@aicw.it<\/p>\n<p>&nbsp;<\/p>\n<p><strong>1\u00b0 tappa &#8211; Funtana Meiga Wave 2022<\/strong>: la quota di iscrizione ammonta ad <strong>\u20ac 80,00<\/strong> a testa e tutte le iscrizioni dovranno essere ratificate presso la segreteria del Referente AICW WAVE e\/o Organizzatore in loco, dalle ore 07.00 alle ore 08.30 del primo giorno di regata.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2\u00b0 tappa -Banzai Wave 2022<\/strong> la quota di iscrizione ammonta ad <strong>\u20ac 80,00<\/strong> a testa e tutte le preiscrizioni dovranno essere ratificate presso la segreteria del Referente AICW WAVE e\/o Organizzatore in loco, dalle ore 07.00 alle ore 08.30 del primo giorno di regata, versando la quota di iscrizione.<\/p>\n<p>&nbsp;<\/p>\n<p>I concorrenti che, per qualsiasi motivo, intendano disdire la propria partecipazione dovranno inviare comunicazione per email al Circolo Organizzatore, i cui recapiti anche di posta elettronica sono indicati al punto 2 del presente bando, ENTRO E NON OLTRE LE ORE 24 DELLA GIORNATA PRECEDENTE L&#8217;INIZIO DELLE COMPETIZIONI. La quota di iscrizione non verr\u00e0 comunque rimborsata.<\/p>\n<p>Ad insindacabile giudizio del Circolo Organizzatore potr\u00e0 essere possibile iscriversi direttamente in loco il primo giorno della regata, entro le ore 08.30 e solo nel caso vi siano posti vacanti nel rispetto di quanto previsto dal qui precedente comma <strong>3<\/strong> (AMMISSIONE, DISCIPLINE E TESSERAMENTO), con l\u2019applicazione di una mora di \u20ac 20,00 oltre la quota di iscrizione (totale iscrizione tardiva \u20ac 100,00).<\/p>\n<p>&nbsp;<\/p>\n<p>In ogni caso alle ore 09.00 del primo giorno di regata, a meno di diversa comunicazione dell&#8217;Organizzatore, saranno tassativamente chiuse e non verr\u00e0 pi\u00f9 ammesso atleta alcuno, indipendentemente dalle cause del ritardo, siano esse personali o di forza maggiore, o dal fatto che abbia o meno tempestivamente avvisato.<\/p>\n<p>I concorrenti potranno prendere parte, pagando la quota completa di iscrizione anche alla sola prima giornata di regata, accettando il risultato di DNC nel caso si effettuino prove nelle giornate seguenti e\/o in loro assenza.<\/p>\n<p>Si comunica inoltre che \u00e8 tassativamente proibito far ratificare la presenza alle regate da colleghi, amici o terze persone. E non sar\u00e0 ugualmente concesso di trasferire, per qualsiasi motivo, la quota di iscrizione da un socio a un altro o da una regata alla successiva.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"7\">\n<li><strong> PUBBLICITA&#8217;<\/strong><\/li>\n<\/ol>\n<p>La Regata \u00e8 classificata \u201ca libera sponsorizzazione\u201d. I concorrenti che espongono pubblicit\u00e0 propria dovranno essere in regola con la licenza FIV per l&#8217;esposizione della pubblicit\u00e0 come da: <a href=\"http:\/\/www.federvela.it\/la-federvela\/content\/pubblicit\u00e0\">http:\/\/www.federvela.it\/la-federvela\/content\/pubblicit\u00e0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Il Circolo Organizzatore e\/o AICW potr\u00e0 richiedere ai concorrenti di esporre un adesivo,\u00a0rappresentante il nome dello Sponsor della Manifestazione,\u00a0su ambedue i lati della vela e\/o sulle pettorine che dovranno essere esposti per l\u2019intera durata della manifestazione, in accordo con la Regulation 20.4 WS.<\/p>\n<p>L&#8217;inosservanza di quest&#8217;ultima norma non potr\u00e0 essere oggetto di protesta tra i concorrenti.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"8\">\n<li><strong> PROGRAMMA<\/strong>:<\/li>\n<\/ol>\n<p>I concorrenti dovranno essere a disposizione del Comitato di Regata la mattina del primo giorno di regata per lo Skipper meeting previsto per le ore 07:30 con possibile inizio gara alle ore 09:00. Durante lo Skipper meeting di ogni giorno verr\u00e0 comunicato il programma orientativo della giornata. Tuttavia, salvo diverse disposizioni pubblicato all&#8217;Albo ufficiale dei comunicati al seguente link: www.aicw.it entro le ore 12.00 dell&#8217;ultimo giorno di gara previsto, nessuna prova potr\u00e0 avere inizio dopo le ore 18.00 del medesimo giorno. E&#8217; fatto <strong><u>obbligo<\/u><\/strong> ai concorrenti di presenziare agli Skipper meeting, in quanto potranno essere comunicate variazioni alle istruzioni di regata.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROGRAMMA Funtana Meiga e Banzai<\/strong>:<\/p>\n<p>&nbsp;<\/p>\n<p>Verr\u00e0 utilizzato il sistema a SEMAFORO per la chiamata della gara:<\/p>\n<p>&nbsp;<\/p>\n<p>SEMAFORO ROSSO: periodo di Stand-by;<\/p>\n<p>&nbsp;<\/p>\n<p>SEMAFORO GIALLO: si accende 96\/72 ore prima del possibile inizio della gara; entro le 24 ore successive all\u2019accensione del giallo vanno date le conferme di iscrizione;<\/p>\n<p>&nbsp;<\/p>\n<p>SEMAFORO VERDE: si accende non meno di 48h prima dell\u2019inizio della gara.<\/p>\n<p>&nbsp;<\/p>\n<p>Il programma dettagliato dell\u2019evento sar\u00e0 a disposizione dei partecipanti a Semaforo GIALLO<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"9\">\n<li><strong>ISPEZIONE DELLE ATTREZZATURE<\/strong><\/li>\n<\/ol>\n<p>I materiali sono liberi.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"10\">\n<li><strong>10<\/strong><strong>. SEDE DELL\u2019EVENTO<\/strong><\/li>\n<\/ol>\n<p><strong>1\u00b0 tappa ORISTANO-FUNTANA MEIGA<\/strong><\/p>\n<p>Circolo Nautico Oristano<\/p>\n<p>Loc. Porticciolo Turistico Torregrande Oristano (OR)<\/p>\n<p>Telefono: 346 03 19 129<\/p>\n<p>Email: <a href=\"mailto:circolonauticooristano@gmail.com\">circolonauticooristano@gmail.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>2\u00b0 tappa SANTA MARINELLA BANZAI \u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Assoc. Sport. Dilett. Velica Ladispoli Surf &amp; Sail<\/p>\n<p>VIA DELLE PRIMULE 15, 00055 Ladispoli, RM<\/p>\n<p>Telefono: 3382466977 &#8211; 3286440270<\/p>\n<p>E-Mail: <a href=\"mailto:info@assovelica.it\">info@assovelica.it<\/a><\/p>\n<p>&nbsp;<\/p>\n<ol start=\"11\">\n<li><strong> PROVE PREVISTE<\/strong>:<\/li>\n<\/ol>\n<p>Verr\u00e0 disputato il maggior numero di prove possibili, in relazione alle condizioni locali, a discrezione del Comitato di Regata.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"12\">\n<li><strong>12<\/strong><strong>.<\/strong> <strong>LIMITE DEL VENTO<\/strong>:<\/li>\n<\/ol>\n<p>Sar\u00e0 discrezione esclusiva del Comitato di Regata valutare l&#8217;effettiva possibilit\u00e0 di disputare o continuare la prova.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"13\">\n<li><strong>13<\/strong><strong>. PUNTEGGIO<\/strong>:<\/li>\n<\/ol>\n<p>Verr\u00e0 applicata l&#8217;appendice A2 del RRS cos\u00ec come modificata dall&#8217;appendice &#8220;B&#8221; con le seguenti modifiche:<\/p>\n<ul>\n<li>al primo classificato verr\u00e0 assegnato il punteggio di 0,7 punti.<\/li>\n<li>scarti: da 1 a 3 tabelloni: nessuno scarto; da 4 a 6 tabelloni: 1 scarti; da 7 a 8 tabelloni: 2 scarti; oltre 9 tabelloni: 3 scarti.<\/li>\n<li>scarti di tappa: fino a 3 Tappe, nessuno scarto, 4-5 tappe verr\u00e0 concesso n. 1 scarto.<\/li>\n<\/ul>\n<p>Ai fini dell\u2019assegnazione del Circuito, si utilizzer\u00e0 il sistema a punti, riceveranno punti i primi 32 concorrenti, secondo la seguente classificazione:<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"63\"><strong>POSN<\/strong><\/td>\n<td width=\"64\"><strong>POINTS<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"63\">1<\/td>\n<td width=\"64\">1030<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">2<\/td>\n<td width=\"64\">1020<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">3<\/td>\n<td width=\"64\">1010<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">4<\/td>\n<td width=\"64\">1000<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">5<\/td>\n<td width=\"64\">990<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">6<\/td>\n<td width=\"64\">980<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">7<\/td>\n<td width=\"64\">970<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">8<\/td>\n<td width=\"64\">960<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">9<\/td>\n<td width=\"64\">950<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">10<\/td>\n<td width=\"64\">940<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">11<\/td>\n<td width=\"64\">930<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">12<\/td>\n<td width=\"64\">920<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">13<\/td>\n<td width=\"64\">910<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">14<\/td>\n<td width=\"64\">900<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">15<\/td>\n<td width=\"64\">890<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">16<\/td>\n<td width=\"64\">880<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">17<\/td>\n<td width=\"64\">870<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">18<\/td>\n<td width=\"64\">860<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">19<\/td>\n<td width=\"64\">850<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">20<\/td>\n<td width=\"64\">840<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">21<\/td>\n<td width=\"64\">830<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">22<\/td>\n<td width=\"64\">820<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">23<\/td>\n<td width=\"64\">810<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">24<\/td>\n<td width=\"64\">800<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">25<\/td>\n<td width=\"64\">790<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">26<\/td>\n<td width=\"64\">780<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">27<\/td>\n<td width=\"64\">770<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">28<\/td>\n<td width=\"64\">760<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">29<\/td>\n<td width=\"64\">750<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">30<\/td>\n<td width=\"64\">740<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">31<\/td>\n<td width=\"64\">730<\/td>\n<\/tr>\n<tr>\n<td width=\"63\">32<\/td>\n<td width=\"64\">720<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"14\">\n<li><strong>14<\/strong><strong>. [DP] PERSONE DI SUPPORTO<\/strong><\/li>\n<\/ol>\n<p><strong>NON PREVISTE<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"15\">\n<li><strong>15<\/strong><strong>. DICHIARAZIONE DI RISCHIO<\/strong>:<\/li>\n<\/ol>\n<p>La RRS 3 cita: &#8220;La responsabilit\u00e0 della decisione di una tavola a vela di partecipare a una prova o di rimanere in regata \u00e8 solo sua.&#8221; Pertanto: partecipando a questo evento ogni regatante riconosce che la vela \u00e8 un&#8217;attivit\u00e0 potenzialmente pericolosa che comporta dei rischi. Questi rischi includono la possibilit\u00e0 di affrontare forti venti e mare mosso, improvvisi cambiamenti del meteo, guasti\/danni alle attrezzature, errori di manovra della tavola a vela, scarsa marineria da parte di altre tavole a vela, perdita di equilibrio dovuta all\u2019instabilit\u00e0 del mezzo e affaticamento con conseguente aumento del rischio di lesioni. <strong>E\u2019 insito nello sport della vela il rischio di lesioni permanenti e gravi o la morte per annegamento, trauma, ipotermia o altre cause<\/strong>.<\/p>\n<p>E\u2019 pertanto responsabilit\u00e0 dei Concorrenti e delle loro Persone di Supporto decidere in base alle loro capacit\u00e0, alla forza del vento, allo stato del mare, alle previsioni meteorologiche ed a tutto quanto altro deve essere previsto da un buon marinaio, se partecipare alle regate, continuarle ovvero di rinunciare.<\/p>\n<p>Gli Organizzatori, il CdR, il CdP e quanti collaboreranno alla manifestazione, declinano ogni e qualsiasi responsabilit\u00e0 per danni che possono subire persone e\/o cose, sia in terra che in acqua, in conseguenza della loro partecipazione alla regata di cui al presente Bando.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"16\">\n<li><strong> [DP][NP] RESPONSABILITA\u2019 AMBIENTALE<\/strong><\/li>\n<\/ol>\n<p>Richiamando il Principio Base che cita: \u201cI partecipanti sono incoraggiati a minimizzare qualsiasi impatto ambientale negativo dello sport della vela\u201d, si raccomanda la massima attenzione per la salvaguardia ambientale in tutti i momenti che accompagnano la pratica dello sport della vela prima, durante e dopo la manifestazione. In particolare si richiama l\u2019attenzione alla RRS 47 -Smaltimento dei Rifiuti- che testualmente cita: \u201cI concorrenti e le persone di supporto non devono gettare deliberatamente rifiuti in acqua. Questa regola si applica sempre quando in acqua. La penalit\u00e0 per un\u2019infrazione a questa regola pu\u00f2 essere inferiore alla squalifica\u201d.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"17\">\n<li><strong> ASSICURAZIONE<\/strong><\/li>\n<\/ol>\n<p>I concorrenti dovranno essere assicurati per la responsabilit\u00e0 civile<\/p>\n<p>per danni a terzi secondo quanto previsto dalle vigenti Normative (FIV) per l\u2019attivit\u00e0 sportiva nazionale organizzata in Italia, con massimale minimo pari a \u20ac 1.500.000,00. (Tale assicurazione \u00e8 gi\u00e0 compresa nel tesseramento AICW).<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"18\">\n<li><strong>PREMI<\/strong><\/li>\n<\/ol>\n<p><strong>1\u00b0-2\u00b0-3\u00b0-Overall<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ol start=\"19\">\n<li><strong>DIRITTI FOTOGRAFICI E\/O TELEVISIVI<\/strong>:<\/li>\n<\/ol>\n<p>Con l&#8217;iscrizione ad una regata ogni concorrente concede automaticamente all&#8217;organizzatore il diritto perpetuo di realizzare, utilizzare e mostrare, in qualsiasi occasione e a discrezione dei medesimi, ogni registrazione audio, immagine fotografica, filmato, ripresa video e TV in diretta o registrata, effettuati durante la suddetta regata alla quale prende parte, senza compenso alcuno. La presenza in acqua di barche di appoggio per i media, cos\u00ec come per gli allenatori o responsabili delle squadre, deve essere autorizzata dal Comitato di Regata.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"20\">\n<li><strong>20<\/strong><strong>. ULTERIORI INFORMAZIONI<\/strong><\/li>\n<\/ol>\n<p>Per ulteriori informazioni \u00e8 possibile contattare i Circoli organizzatori, ai riferimenti del punto 10 del presente bando.<\/p>\n<p>Eventualmente \u00e8 possibile contattare il Consigliere A.I.C.W. Matteo Spanu Responsabile settore artistico al 3496167147 o mail: matteospanu@tiscali.it<\/p>\n<p><a href=\"http:\/\/www.aicw.it\/wp-content\/uploads\/2022\/02\/BANDO-CAMPIONATO-ITALIANO-WAVE-2022-FINALE.pdf\">BANDO CAMPIONATO ITALIANO WAVE 2022 FINALE<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MODULO ISCRIZIONE ONLINE <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14587\" src=\"http:\/\/www.aicw.it\/wp-content\/uploads\/2022\/02\/wave_qrcode_muse.png\" alt=\"\" width=\"178\" height=\"178\" srcset=\"https:\/\/www.aicw.it\/wp-content\/uploads\/2022\/02\/wave_qrcode_muse.png 400w, https:\/\/www.aicw.it\/wp-content\/uploads\/2022\/02\/wave_qrcode_muse-300x300.png 300w, https:\/\/www.aicw.it\/wp-content\/uploads\/2022\/02\/wave_qrcode_muse-150x150.png 150w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CIRCOLO NAUTICO ORISTANO (su delega della FIV -Federazione Italiana Vela- e in collaborazione con A.I.C.W. E Assoc. Sport. Dilett. Velica Ladispoli- Banzai\u00a0 A.S.D. (su delega della FIV -Federazione Italiana Vela- e in collaborazione con A.I.C.W. Campionato Italiano WAVE 2022 &nbsp; 1^ Tappa Funtana Meiga Waiting Period dal 1\/03\/2022 al 30\/04\/2022 2^ Tappa Banzai Waiting Period [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,4],"tags":[89,88,20,87],"class_list":["post-14586","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bandi-regata","category-latest-news","category-news","tag-banzai","tag-funtana-meiga","tag-wave","tag-wave-campionato","czr-hentry"],"_links":{"self":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/14586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/comments?post=14586"}],"version-history":[{"count":3,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/14586\/revisions"}],"predecessor-version":[{"id":14591,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/14586\/revisions\/14591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media\/13850"}],"wp:attachment":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media?parent=14586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/categories?post=14586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/tags?post=14586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}