{"id":11816,"date":"2019-05-02T11:56:04","date_gmt":"2019-05-02T09:56:04","guid":{"rendered":"http:\/\/www.aicw.it\/?p=11816"},"modified":"2019-05-03T13:49:32","modified_gmt":"2019-05-03T11:49:32","slug":"1-tappa-coppa-italia-fw","status":"publish","type":"post","link":"https:\/\/www.aicw.it\/index.php\/2019\/05\/02\/1-tappa-coppa-italia-fw\/","title":{"rendered":"1 TAPPA COPPA ITALIA FW 2019 PORTO CORSINI"},"content":{"rendered":"<h2 style=\"text-align: center;\">COPPA ITALIA FORMULA WINDSURFING 2019<\/h2>\n<h2 style=\"text-align: center;\">LA PRIMA TAPPA 2019 A PORTO CORSINI (RA) PER IL MEMORIAL<\/h2>\n<h2 style=\"text-align: center;\">BALLANTI SAIANI<\/h2>\n<div>Adriatico Wind Club &#8211; 11-12 maggio 2019<\/div>\n<div><\/div>\n<div>Torna la Coppa Italia di Formula Windsurfing e ad ospitare la prima tappa del 2019, il weekend del 11 e 12 maggio, \u00e8 l&#8217;Adriatico Wind Club di Porto Corsini, Ravenna. La gara, valida anche come prima tappa di specialit\u00e0 del circuito del Medio-Adriatico, assegna il premio del Memorial Ballanti-Saiani, che ogni anno, a primavera, ricorda le due atlete, Lorenza e Dalia, prematuramente scomparse. Insieme alla Coppa Italia di Formula, il Memorial ospita contemporaneamente, per due giorni di grande sport sull&#8217;acqua, altre Classi Federali.<\/div>\n<div><\/div>\n<div>\u201cLa tappa di Coppa Italia Formula Windsurfing \u2013 spiega Fabio Benericetti, responsabile zona XI Emilia Romagna dell&#8217;AICW \u2013 sar\u00e0 un evento importante al quale parteciperanno gli amici della classe Windsurfer, ed i ragazzi della classe Tecno 293, per disputare una tappa del circuito zonale. Per un totale, si stima, tra gli 80 e i 100 windsurf in acqua. Vorrei evidenziare, che da quest&#8217;anno abbiamo inserito nella Coppa Italia la divisione Experimental Foil, per la quale sono ammesse tavole di serie con larghezza massima di 100.5 cm, e devono essere dichiarate tre vele e due Foil. Ed infine, l&#8217;inserimento della Categoria Esordienti per la Formula Windsurfing, (non valida per la Classifica Ufficiale della Coppa Italia FW), categoria nata dall&#8217;idea di Andrea Volpini (delegato della IV Zona Regione Lazio) per dare l&#8217;opportunit\u00e0 a chi inizia a partecipare alle regate Formula, di stare il pi\u00f9 possibile assieme alla flotta dei pi\u00f9 esperti, visto che le prove per gli esordienti equivalgono al completamento di un giro del percorso invece di due\u201d.<\/div>\n<div>Alla fine degli anni Novanta, nacque il concetto della Formula Windsurfing. La filosofia che ispirava il progetto era molto semplice: dichiarare all\u2019atto dell\u2019iscrizione a una regata una sola tavola e tre vele; introdurre un limite minimo di vento di 7 nodi in partenza fino a un minuto dopo il via e lasciare successivamente al Comitato di Regata la valutazione se la gara potesse procedere regolarmente, sulla scorta di un\u2019estimazione sulle condizioni plananti per la flotta. Una vera e propria rivoluzione rispetto alla mole di attrezzatura necessaria per il Funboard e agli alti limiti di vento minimo e costante richiesti soprattutto per lo Slalom (al tempo 13 nodi), oggi 11 nodi Un\u2019innovazione che non poteva che trovare adepti in Italia, dove il vento forte \u00e8, salvo rari casi, una condizione non diffusa. In sintesi: maggiori possibilit\u00e0 di regate valide; minori costi per un\u2019attrezzatura competitiva.<\/div>\n<div>Il circolo Adriatico Wind Club, fondato nel 1988,\u00e8 ubicato sul litorale ravennate, all\u2019inizio della diga nord di Porto Corsini, quindi in una posizione ottimale. La diga, si inoltra per ben 2.500 mt nel mare Adriatico ed \u00e8 meta di ritrovo e di passeggio, per migliaia di persone. Il circolo dispone di 15.000 mq. Di spiaggia,di un edificio con bar, ristorante, uffici, spogliatoi e bagni, conta oltre 700 soci.<\/div>\n<div>Ravenna -Adriatico Wind Club &#8211; Via Teseo Guerra, 25 \u2013 48010 Porto Corsini (RA). Tel. 0544\/448222 segreteria tel\/fax 0544 448233 &#8211; <a href=\"mailto:info@adriaticowindclub.com\" target=\"_blank\" rel=\"noopener noreferrer\">info@adriaticowindclub.com<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COPPA ITALIA FORMULA WINDSURFING 2019 LA PRIMA TAPPA 2019 A PORTO CORSINI (RA) PER IL MEMORIAL BALLANTI SAIANI Adriatico Wind Club &#8211; 11-12 maggio 2019 Torna la Coppa Italia di Formula Windsurfing e ad ospitare la prima tappa del 2019, il weekend del 11 e 12 maggio, \u00e8 l&#8217;Adriatico Wind Club di Porto Corsini, Ravenna. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-11816","post","type-post","status-publish","format-standard","category-latest-news","category-news","czr-hentry"],"_links":{"self":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/11816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/comments?post=11816"}],"version-history":[{"count":2,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/11816\/revisions"}],"predecessor-version":[{"id":11818,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/posts\/11816\/revisions\/11818"}],"wp:attachment":[{"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/media?parent=11816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/categories?post=11816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aicw.it\/index.php\/wp-json\/wp\/v2\/tags?post=11816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}